{"id":25,"date":"2018-09-02T21:30:53","date_gmt":"2018-09-02T19:30:53","guid":{"rendered":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/"},"modified":"2024-07-20T21:36:56","modified_gmt":"2024-07-20T19:36:56","slug":"ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad","status":"publish","type":"product","link":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/","title":{"rendered":"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad"},"content":{"rendered":"<p>La Gu\u00eda de actuaci\u00f3n en la empresa tras el fin de la ultraactividad para evitar los efectos perjudiciales de la falta de convenio colectivo, le muestra paso a paso, en sus 73 p\u00e1ginas, como dar forma a las relaciones laborales cuando ya no hay un colectivo que se pueda aplicar en la empresa, de forma que sin tener que tomar el Estatuto de los Trabajadores como base para las mismas, no se sea posible que se pueda considerar que existe un condici\u00f3n m\u00e1s beneficiosa cuando vuelva a existir un convenio colectivo de aplicaci\u00f3n. <\/p>\n<p><strong>\u00cdndice<\/strong><\/p>\n<p><strong>1. Elementos B\u00e1sicos<\/strong><\/p>\n<ul>\n<li>\u00bfQu\u00e9 es la ultraactividad?<\/li>\n<li>\u00bfCu\u00e1l es el plazo para que deje de aplicarse el convenio colectivo?<\/li>\n<li>\u00bfEs posible prorrogar el periodo de ultraactividad del convenio?<\/li>\n<li>\u00bfQu\u00e9 tr\u00e1mites hay que realizar para que el cese del convenio se haga efectivo?<\/li>\n<li>\u00bfQu\u00e9 se considera un convenio de \u00e1mbito superior?<\/li>\n<li>\u00bfCu\u00e1ndo existen varios convenios que pueden serle de aplicaci\u00f3n a la empresa, hay que ir obligatoriamente al de \u00e1mbito superior?<\/li>\n<li>\u00bfC\u00f3mo se decide qu\u00e9 convenio se aplica en la empresa, si existen varios que pueden serle de aplicaci\u00f3n?<\/li>\n<li>\u00bfQui\u00e9n decide cu\u00e1l es el nuevo convenio que se aplica?<\/li>\n<li>\u00bfC\u00f3mo se regulan las cuestiones que no fueron tenidas en cuenta en el convenio de \u00e1mbito superior y que s\u00ed estaban tratadas en el convenio cesado?<\/li>\n<li>\u00bfC\u00f3mo se regula la relaci\u00f3n con los trabajadores si no existe convenio superior aplicable?<\/li>\n<li>\u00bfEs posible que los trabajadores tengan que regirse directamente por el Estatuto de los Trabajadores?<\/li>\n<li>\u00bfQu\u00e9 se considera como una decisi\u00f3n unilateral de la empresa con efectos colectivos?<\/li>\n<li>\u00bfQu\u00e9 sucede con los convenios extraestatutarios?<\/li>\n<li>Si no existen tablas salariales,\u00bf qu\u00e9 sucede con el salario de los trabajadores?, \u00bfpasa a ser el SMI?<\/li>\n<li>\u00bfC\u00f3mo se puede mantener el nivel salarial de los trabajadores sin incurrir en una condici\u00f3n m\u00e1s beneficiosa y aplicando el SMI?<\/li>\n<li>\u00bfC\u00f3mo se evita que a las condiciones laborales de los trabajadores, adoptadas de forma unilateral por la empresa, se las pueda considerar como condici\u00f3n m\u00e1s beneficiosa?<\/li>\n<li>\u00bfCu\u00e1ndo se podr\u00eda recurrir al proceso de modificaci\u00f3n sustancial de las condiciones de trabajo?\n<\/li>\n<\/ul>\n<p><strong>2. Documentos Modelo<\/strong><\/p>\n<ul>\n<li>Documento Modelo de Decisi\u00f3n Unilateral de la Empresa de Efectos Colectivos cuando el convenio colectivo de \u00e1mbito superior no regula determinados aspectos que si aparec\u00edan en el convenio cesado.<\/li>\n<li>Documento Modelo de Decisi\u00f3n Unilateral de la Empresa de Efectos Colectivos cuando no existe convenio colectivo de \u00e1mbito superior.<\/li>\n<li>Comunicaci\u00f3n a los representantes de los trabajadores del cese de la efectividad del convenio por fin de la ultraatividad, instando a la negociaci\u00f3n de nuevas condiciones de trabajo.<\/li>\n<li>Documento Modelo de Pacto con los representantes legales de los trabajadores sobre el acuerdo de las condiciones laborales tras el cese la ultraactividad cuando el convenio colectivo de \u00e1mbito superior no regule determinados aspectos que s\u00ed aparec\u00edan en el convenio cesado.<\/li>\n<li>Documento Modelo de Pacto con los representes legales de los trabajadores sobre el acuerdo de condiciones laborales tras el cese la ultraactividad cuando no existe convenio colectivo de \u00e1mbito superior.<\/li>\n<li>Documento Modelo de comunicaci\u00f3n a los trabajadores del nuevo convenio de aplicaci\u00f3n en la empresa.<\/li>\n<li>Documento Modelo de comunicaci\u00f3n a los trabajadores de nuevas condiciones salariales.\n<\/li>\n<\/ul>\n<p><strong>3. Anexo. Extracto de Jurisprudencia<\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consecuencia del fin de la ultraactividad, tal como detalla el art. 86.3 del Estatuto de los Trabajadores: \u201cTranscurrido un a\u00f1o desde la denuncia del convenio colectivo sin que se haya acordado un nuevo convenio o dictado un laudo arbitral, aqu\u00e9l perder\u00e1, salvo pacto en contrario, su vigencia y se aplicar\u00e1, si lo hubiere, el convenio colectivo de \u00e1mbito superior que fuera de aplicaci\u00f3n\u201d.<\/p>\n","protected":false},"featured_media":188,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_cat":[18],"product_tag":[65,64,66,67],"class_list":["post-25","product","type-product","status-publish","has-post-thumbnail","product_cat-inicio","product_tag-colectivo","product_tag-convenio","product_tag-guia","product_tag-ultraactividad","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad - La Librer\u00eda de Ayuda Laboral<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad - La Librer\u00eda de Ayuda Laboral\" \/>\n<meta property=\"og:description\" content=\"La consecuencia del fin de la ultraactividad, tal como detalla el art. 86.3 del Estatuto de los Trabajadores: \u201cTranscurrido un a\u00f1o desde la denuncia del convenio colectivo sin que se haya acordado un nuevo convenio o dictado un laudo arbitral, aqu\u00e9l perder\u00e1, salvo pacto en contrario, su vigencia y se aplicar\u00e1, si lo hubiere, el convenio colectivo de \u00e1mbito superior que fuera de aplicaci\u00f3n\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/\" \/>\n<meta property=\"og:site_name\" content=\"La Librer\u00eda de Ayuda Laboral\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-20T19:36:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png\" \/>\n\t<meta property=\"og:image:width\" content=\"386\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/\",\"url\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/\",\"name\":\"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad - La Librer\u00eda de Ayuda Laboral\",\"isPartOf\":{\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png\",\"datePublished\":\"2018-09-02T19:30:53+00:00\",\"dateModified\":\"2024-07-20T19:36:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#primaryimage\",\"url\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png\",\"contentUrl\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png\",\"width\":386,\"height\":567,\"caption\":\"Portada Ultraactividad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1 La Librer\u00eda\",\"item\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/#website\",\"url\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/\",\"name\":\"La Libreria de Ayuda Laboral\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/#organization\",\"name\":\"La Libreria de Ayuda Laboral\",\"url\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2024\/07\/templates_al_logo.png\",\"contentUrl\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2024\/07\/templates_al_logo.png\",\"width\":305,\"height\":86,\"caption\":\"La Libreria de Ayuda Laboral\"},\"image\":{\"@id\":\"https:\/\/www.ayudalaboral.net\/lalibreria\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad - La Librer\u00eda de Ayuda Laboral","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/","og_locale":"es_ES","og_type":"article","og_title":"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad - La Librer\u00eda de Ayuda Laboral","og_description":"La consecuencia del fin de la ultraactividad, tal como detalla el art. 86.3 del Estatuto de los Trabajadores: \u201cTranscurrido un a\u00f1o desde la denuncia del convenio colectivo sin que se haya acordado un nuevo convenio o dictado un laudo arbitral, aqu\u00e9l perder\u00e1, salvo pacto en contrario, su vigencia y se aplicar\u00e1, si lo hubiere, el convenio colectivo de \u00e1mbito superior que fuera de aplicaci\u00f3n\u201d.","og_url":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/","og_site_name":"La Librer\u00eda de Ayuda Laboral","article_modified_time":"2024-07-20T19:36:56+00:00","og_image":[{"width":386,"height":567,"url":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/","url":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/","name":"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad - La Librer\u00eda de Ayuda Laboral","isPartOf":{"@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#primaryimage"},"image":{"@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png","datePublished":"2018-09-02T19:30:53+00:00","dateModified":"2024-07-20T19:36:56+00:00","breadcrumb":{"@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#primaryimage","url":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png","contentUrl":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2018\/09\/Ultraactividad.-Guia-RRLL-tras-el-fin-de-la-ultraactividad.png","width":386,"height":567,"caption":"Portada Ultraactividad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/producto\/ultraactividad-guia-rrll-tras-el-fin-de-la-ultraactividad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ayudalaboral.net\/lalibreria\/"},{"@type":"ListItem","position":2,"name":"1 La Librer\u00eda","item":"https:\/\/www.ayudalaboral.net\/lalibreria\/tienda\/"},{"@type":"ListItem","position":3,"name":"Ultraactividad. Gu\u00eda RRLL tras el fin de la ultraactividad"}]},{"@type":"WebSite","@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/#website","url":"https:\/\/www.ayudalaboral.net\/lalibreria\/","name":"La Libreria de Ayuda Laboral","description":"","publisher":{"@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ayudalaboral.net\/lalibreria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/#organization","name":"La Libreria de Ayuda Laboral","url":"https:\/\/www.ayudalaboral.net\/lalibreria\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/#\/schema\/logo\/image\/","url":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2024\/07\/templates_al_logo.png","contentUrl":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-content\/uploads\/2024\/07\/templates_al_logo.png","width":305,"height":86,"caption":"La Libreria de Ayuda Laboral"},"image":{"@id":"https:\/\/www.ayudalaboral.net\/lalibreria\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/product\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":0,"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/product\/25\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/media\/188"}],"wp:attachment":[{"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/product_cat?post=25"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ayudalaboral.net\/lalibreria\/wp-json\/wp\/v2\/product_tag?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}